{"id":181,"date":"2020-04-09T10:18:36","date_gmt":"2020-04-09T08:18:36","guid":{"rendered":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/?p=181"},"modified":"2020-04-09T10:18:37","modified_gmt":"2020-04-09T08:18:37","slug":"atelier-brushing-aux-maisons-de-la-touche","status":"publish","type":"post","link":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/","title":{"rendered":"Atelier brushing aux Maisons de la Touche"},"content":{"rendered":"\n<p>Aux Maisons de la Touche, le personnel soignant se transforme en coiffeur le temps d&rsquo;un instant. <\/p>\n\n\n\n<p>Le brushing fait, les r\u00e9sidents bien coiff\u00e9s sont pr\u00eats pour leur session Skype ! <\/p>\n\n\n\n<p>Il faudra cependant attendre pour les couleurs et les coupes qui n\u00e9cessitent, pour le bien-\u00eatre capillaire des r\u00e9sidents, une coiffeuse exp\u00e9riment\u00e9e&#8230;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2020\/04\/1-scaled-e1586178962181-768x1024.jpg\" alt=\"\" class=\"wp-image-178\" width=\"384\" height=\"512\" srcset=\"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2020\/04\/1-scaled-e1586178962181-768x1024.jpg 768w, https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2020\/04\/1-scaled-e1586178962181-225x300.jpg 225w, https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2020\/04\/1-scaled-e1586178962181-1152x1536.jpg 1152w, https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2020\/04\/1-scaled-e1586178962181-1536x2048.jpg 1536w, https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2020\/04\/1-scaled-e1586178962181-750x1000.jpg 750w, https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2020\/04\/1-scaled-e1586178962181.jpg 1920w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Aux Maisons de la Touche, le personnel soignant se transforme en coiffeur le temps d&rsquo;un instant. Le brushing fait, les r\u00e9sidents bien coiff\u00e9s sont pr\u00eats pour leur session Skype ! Il faudra cependant attendre pour les couleurs et les coupes qui n\u00e9cessitent, pour le bien-\u00eatre capillaire des r\u00e9sidents, une coiffeuse exp\u00e9riment\u00e9e&#8230;<\/p>\n","protected":false},"author":15,"featured_media":179,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atelier brushing aux Maisons de la Touche - Les Maisons de la Touche<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atelier brushing aux Maisons de la Touche - Les Maisons de la Touche\" \/>\n<meta property=\"og:description\" content=\"Aux Maisons de la Touche, le personnel soignant se transforme en coiffeur le temps d&rsquo;un instant. Le brushing fait, les r\u00e9sidents bien coiff\u00e9s sont pr\u00eats pour leur session Skype ! Il faudra cependant attendre pour les couleurs et les coupes qui n\u00e9cessitent, pour le bien-\u00eatre capillaire des r\u00e9sidents, une coiffeuse exp\u00e9riment\u00e9e&#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Maisons de la Touche\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-09T08:18:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-09T08:18:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2020\/04\/2-scaled-e1586178979437.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"latouche77kg9v3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"latouche77kg9v3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2020\\\/04\\\/09\\\/atelier-brushing-aux-maisons-de-la-touche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2020\\\/04\\\/09\\\/atelier-brushing-aux-maisons-de-la-touche\\\/\"},\"author\":{\"name\":\"latouche77kg9v3n\",\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/#\\\/schema\\\/person\\\/a50e2713df038cb6d0095423f86b9831\"},\"headline\":\"Atelier brushing aux Maisons de la Touche\",\"datePublished\":\"2020-04-09T08:18:36+00:00\",\"dateModified\":\"2020-04-09T08:18:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2020\\\/04\\\/09\\\/atelier-brushing-aux-maisons-de-la-touche\\\/\"},\"wordCount\":66,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2020\\\/04\\\/09\\\/atelier-brushing-aux-maisons-de-la-touche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/04\\\/2-scaled-e1586178979437.jpg\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2020\\\/04\\\/09\\\/atelier-brushing-aux-maisons-de-la-touche\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2020\\\/04\\\/09\\\/atelier-brushing-aux-maisons-de-la-touche\\\/\",\"url\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2020\\\/04\\\/09\\\/atelier-brushing-aux-maisons-de-la-touche\\\/\",\"name\":\"Atelier brushing aux Maisons de la Touche - Les Maisons de la Touche\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2020\\\/04\\\/09\\\/atelier-brushing-aux-maisons-de-la-touche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2020\\\/04\\\/09\\\/atelier-brushing-aux-maisons-de-la-touche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/04\\\/2-scaled-e1586178979437.jpg\",\"datePublished\":\"2020-04-09T08:18:36+00:00\",\"dateModified\":\"2020-04-09T08:18:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/#\\\/schema\\\/person\\\/a50e2713df038cb6d0095423f86b9831\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2020\\\/04\\\/09\\\/atelier-brushing-aux-maisons-de-la-touche\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2020\\\/04\\\/09\\\/atelier-brushing-aux-maisons-de-la-touche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2020\\\/04\\\/09\\\/atelier-brushing-aux-maisons-de-la-touche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/04\\\/2-scaled-e1586178979437.jpg\",\"contentUrl\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2020\\\/04\\\/2-scaled-e1586178979437.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2020\\\/04\\\/09\\\/atelier-brushing-aux-maisons-de-la-touche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atelier brushing aux Maisons de la Touche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/#website\",\"url\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/\",\"name\":\"Les Maisons de la Touche\",\"description\":\"EHPAD - H\u00c9BERGEMENT TEMPORAIRE - PASA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/#\\\/schema\\\/person\\\/a50e2713df038cb6d0095423f86b9831\",\"name\":\"latouche77kg9v3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb1305dc73959a9bf685ebf0fc342515e06611546c1ca6bc7b3c61f29932cfd2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb1305dc73959a9bf685ebf0fc342515e06611546c1ca6bc7b3c61f29932cfd2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb1305dc73959a9bf685ebf0fc342515e06611546c1ca6bc7b3c61f29932cfd2?s=96&d=mm&r=g\",\"caption\":\"latouche77kg9v3n\"},\"sameAs\":[\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/\"],\"url\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/author\\\/latouche77kg9v3n\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atelier brushing aux Maisons de la Touche - Les Maisons de la Touche","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/","og_locale":"fr_FR","og_type":"article","og_title":"Atelier brushing aux Maisons de la Touche - Les Maisons de la Touche","og_description":"Aux Maisons de la Touche, le personnel soignant se transforme en coiffeur le temps d&rsquo;un instant. Le brushing fait, les r\u00e9sidents bien coiff\u00e9s sont pr\u00eats pour leur session Skype ! Il faudra cependant attendre pour les couleurs et les coupes qui n\u00e9cessitent, pour le bien-\u00eatre capillaire des r\u00e9sidents, une coiffeuse exp\u00e9riment\u00e9e&#8230;","og_url":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/","og_site_name":"Les Maisons de la Touche","article_published_time":"2020-04-09T08:18:36+00:00","article_modified_time":"2020-04-09T08:18:37+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2020\/04\/2-scaled-e1586178979437.jpg","type":"image\/jpeg"}],"author":"latouche77kg9v3n","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"latouche77kg9v3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/#article","isPartOf":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/"},"author":{"name":"latouche77kg9v3n","@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/#\/schema\/person\/a50e2713df038cb6d0095423f86b9831"},"headline":"Atelier brushing aux Maisons de la Touche","datePublished":"2020-04-09T08:18:36+00:00","dateModified":"2020-04-09T08:18:37+00:00","mainEntityOfPage":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/"},"wordCount":66,"commentCount":0,"image":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/#primaryimage"},"thumbnailUrl":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2020\/04\/2-scaled-e1586178979437.jpg","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/","url":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/","name":"Atelier brushing aux Maisons de la Touche - Les Maisons de la Touche","isPartOf":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/#website"},"primaryImageOfPage":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/#primaryimage"},"image":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/#primaryimage"},"thumbnailUrl":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2020\/04\/2-scaled-e1586178979437.jpg","datePublished":"2020-04-09T08:18:36+00:00","dateModified":"2020-04-09T08:18:37+00:00","author":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/#\/schema\/person\/a50e2713df038cb6d0095423f86b9831"},"breadcrumb":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/#primaryimage","url":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2020\/04\/2-scaled-e1586178979437.jpg","contentUrl":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2020\/04\/2-scaled-e1586178979437.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2020\/04\/09\/atelier-brushing-aux-maisons-de-la-touche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/"},{"@type":"ListItem","position":2,"name":"Atelier brushing aux Maisons de la Touche"}]},{"@type":"WebSite","@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/#website","url":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/","name":"Les Maisons de la Touche","description":"EHPAD - H\u00c9BERGEMENT TEMPORAIRE - PASA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/#\/schema\/person\/a50e2713df038cb6d0095423f86b9831","name":"latouche77kg9v3n","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bb1305dc73959a9bf685ebf0fc342515e06611546c1ca6bc7b3c61f29932cfd2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb1305dc73959a9bf685ebf0fc342515e06611546c1ca6bc7b3c61f29932cfd2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb1305dc73959a9bf685ebf0fc342515e06611546c1ca6bc7b3c61f29932cfd2?s=96&d=mm&r=g","caption":"latouche77kg9v3n"},"sameAs":["https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/"],"url":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/author\/latouche77kg9v3n\/"}]}},"_links":{"self":[{"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/posts\/181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/comments?post=181"}],"version-history":[{"count":2,"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/posts\/181\/revisions"}],"predecessor-version":[{"id":184,"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/posts\/181\/revisions\/184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/media\/179"}],"wp:attachment":[{"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/media?parent=181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/categories?post=181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/tags?post=181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}