{"id":118,"date":"2019-05-15T12:31:35","date_gmt":"2019-05-15T10:31:35","guid":{"rendered":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/?p=118"},"modified":"2019-11-15T12:31:59","modified_gmt":"2019-11-15T11:31:59","slug":"tournois-de-jeux-de-societe","status":"publish","type":"post","link":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/","title":{"rendered":"Tournois de jeux de soci\u00e9t\u00e9"},"content":{"rendered":"<p>Certains r\u00e9sidents de la maison des ateliers sont venus nous rendre visite lundi 13 mai.<\/p>\n<p>Un tournoi de jeux de soci\u00e9t\u00e9 a permis aux r\u00e9sidents des 2 maisons ISATIS de \u00ab\u00a0s&rsquo;affronter\u00a0\u00bb amicalement autour d&rsquo;une partie de scrabble, de belote, de triomino&#8230;<br \/>\nLes r\u00e9sidents avaient pr\u00e9par\u00e9 des gateaux le matin afin de rendre cet apr\u00e8s-midi encore plus agr\u00e9able.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Certains r\u00e9sidents de la maison des ateliers sont venus nous rendre visite lundi 13 mai. Un tournoi de jeux de soci\u00e9t\u00e9 a permis aux r\u00e9sidents des 2 maisons ISATIS de \u00ab\u00a0s&rsquo;affronter\u00a0\u00bb amicalement autour d&rsquo;une partie de scrabble, de belote, de triomino&#8230; Les r\u00e9sidents avaient pr\u00e9par\u00e9 des gateaux le matin afin de rendre cet apr\u00e8s-midi encore [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":112,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tournois de jeux de soci\u00e9t\u00e9 - Les Maisons de la Touche<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tournois de jeux de soci\u00e9t\u00e9 - Les Maisons de la Touche\" \/>\n<meta property=\"og:description\" content=\"Certains r\u00e9sidents de la maison des ateliers sont venus nous rendre visite lundi 13 mai. Un tournoi de jeux de soci\u00e9t\u00e9 a permis aux r\u00e9sidents des 2 maisons ISATIS de \u00ab\u00a0s&rsquo;affronter\u00a0\u00bb amicalement autour d&rsquo;une partie de scrabble, de belote, de triomino&#8230; Les r\u00e9sidents avaient pr\u00e9par\u00e9 des gateaux le matin afin de rendre cet apr\u00e8s-midi encore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Maisons de la Touche\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-15T10:31:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-15T11:31:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2019\/11\/e9cb634a382fcc935629c0d45b22997e74b2ba36.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin-JvSCLhrNBE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-JvSCLhrNBE\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2019\\\/05\\\/15\\\/tournois-de-jeux-de-societe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2019\\\/05\\\/15\\\/tournois-de-jeux-de-societe\\\/\"},\"author\":{\"name\":\"admin-JvSCLhrNBE\",\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/#\\\/schema\\\/person\\\/943b5c9342f7eca9dde826898907ac00\"},\"headline\":\"Tournois de jeux de soci\u00e9t\u00e9\",\"datePublished\":\"2019-05-15T10:31:35+00:00\",\"dateModified\":\"2019-11-15T11:31:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2019\\\/05\\\/15\\\/tournois-de-jeux-de-societe\\\/\"},\"wordCount\":71,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2019\\\/05\\\/15\\\/tournois-de-jeux-de-societe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/11\\\/e9cb634a382fcc935629c0d45b22997e74b2ba36.jpg\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2019\\\/05\\\/15\\\/tournois-de-jeux-de-societe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2019\\\/05\\\/15\\\/tournois-de-jeux-de-societe\\\/\",\"url\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2019\\\/05\\\/15\\\/tournois-de-jeux-de-societe\\\/\",\"name\":\"Tournois de jeux de soci\u00e9t\u00e9 - Les Maisons de la Touche\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2019\\\/05\\\/15\\\/tournois-de-jeux-de-societe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2019\\\/05\\\/15\\\/tournois-de-jeux-de-societe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/11\\\/e9cb634a382fcc935629c0d45b22997e74b2ba36.jpg\",\"datePublished\":\"2019-05-15T10:31:35+00:00\",\"dateModified\":\"2019-11-15T11:31:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/#\\\/schema\\\/person\\\/943b5c9342f7eca9dde826898907ac00\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2019\\\/05\\\/15\\\/tournois-de-jeux-de-societe\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2019\\\/05\\\/15\\\/tournois-de-jeux-de-societe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2019\\\/05\\\/15\\\/tournois-de-jeux-de-societe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/11\\\/e9cb634a382fcc935629c0d45b22997e74b2ba36.jpg\",\"contentUrl\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2019\\\/11\\\/e9cb634a382fcc935629c0d45b22997e74b2ba36.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/2019\\\/05\\\/15\\\/tournois-de-jeux-de-societe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tournois de jeux de soci\u00e9t\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/#website\",\"url\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/\",\"name\":\"Les Maisons de la Touche\",\"description\":\"EHPAD - H\u00c9BERGEMENT TEMPORAIRE - PASA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/#\\\/schema\\\/person\\\/943b5c9342f7eca9dde826898907ac00\",\"name\":\"admin-JvSCLhrNBE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/304b15a49c4ff21bb5bc68be1b5a77972169f0608361401c9f9676ec044d15dc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/304b15a49c4ff21bb5bc68be1b5a77972169f0608361401c9f9676ec044d15dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/304b15a49c4ff21bb5bc68be1b5a77972169f0608361401c9f9676ec044d15dc?s=96&d=mm&r=g\",\"caption\":\"admin-JvSCLhrNBE\"},\"url\":\"https:\\\/\\\/isatis.asso.fr\\\/les-maisons-de-la-touche\\\/author\\\/admin-jvsclhrnbe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tournois de jeux de soci\u00e9t\u00e9 - Les Maisons de la Touche","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/","og_locale":"fr_FR","og_type":"article","og_title":"Tournois de jeux de soci\u00e9t\u00e9 - Les Maisons de la Touche","og_description":"Certains r\u00e9sidents de la maison des ateliers sont venus nous rendre visite lundi 13 mai. Un tournoi de jeux de soci\u00e9t\u00e9 a permis aux r\u00e9sidents des 2 maisons ISATIS de \u00ab\u00a0s&rsquo;affronter\u00a0\u00bb amicalement autour d&rsquo;une partie de scrabble, de belote, de triomino&#8230; Les r\u00e9sidents avaient pr\u00e9par\u00e9 des gateaux le matin afin de rendre cet apr\u00e8s-midi encore [&hellip;]","og_url":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/","og_site_name":"Les Maisons de la Touche","article_published_time":"2019-05-15T10:31:35+00:00","article_modified_time":"2019-11-15T11:31:59+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2019\/11\/e9cb634a382fcc935629c0d45b22997e74b2ba36.jpg","type":"image\/jpeg"}],"author":"admin-JvSCLhrNBE","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin-JvSCLhrNBE"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/#article","isPartOf":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/"},"author":{"name":"admin-JvSCLhrNBE","@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/#\/schema\/person\/943b5c9342f7eca9dde826898907ac00"},"headline":"Tournois de jeux de soci\u00e9t\u00e9","datePublished":"2019-05-15T10:31:35+00:00","dateModified":"2019-11-15T11:31:59+00:00","mainEntityOfPage":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/"},"wordCount":71,"commentCount":0,"image":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/#primaryimage"},"thumbnailUrl":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2019\/11\/e9cb634a382fcc935629c0d45b22997e74b2ba36.jpg","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/","url":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/","name":"Tournois de jeux de soci\u00e9t\u00e9 - Les Maisons de la Touche","isPartOf":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/#website"},"primaryImageOfPage":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/#primaryimage"},"image":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/#primaryimage"},"thumbnailUrl":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2019\/11\/e9cb634a382fcc935629c0d45b22997e74b2ba36.jpg","datePublished":"2019-05-15T10:31:35+00:00","dateModified":"2019-11-15T11:31:59+00:00","author":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/#\/schema\/person\/943b5c9342f7eca9dde826898907ac00"},"breadcrumb":{"@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/#primaryimage","url":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2019\/11\/e9cb634a382fcc935629c0d45b22997e74b2ba36.jpg","contentUrl":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-content\/uploads\/sites\/22\/2019\/11\/e9cb634a382fcc935629c0d45b22997e74b2ba36.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/2019\/05\/15\/tournois-de-jeux-de-societe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/"},{"@type":"ListItem","position":2,"name":"Tournois de jeux de soci\u00e9t\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/#website","url":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/","name":"Les Maisons de la Touche","description":"EHPAD - H\u00c9BERGEMENT TEMPORAIRE - PASA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/#\/schema\/person\/943b5c9342f7eca9dde826898907ac00","name":"admin-JvSCLhrNBE","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/304b15a49c4ff21bb5bc68be1b5a77972169f0608361401c9f9676ec044d15dc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/304b15a49c4ff21bb5bc68be1b5a77972169f0608361401c9f9676ec044d15dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/304b15a49c4ff21bb5bc68be1b5a77972169f0608361401c9f9676ec044d15dc?s=96&d=mm&r=g","caption":"admin-JvSCLhrNBE"},"url":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/author\/admin-jvsclhrnbe\/"}]}},"_links":{"self":[{"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/posts\/118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/comments?post=118"}],"version-history":[{"count":1,"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/posts\/118\/revisions"}],"predecessor-version":[{"id":119,"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/posts\/118\/revisions\/119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/media\/112"}],"wp:attachment":[{"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/media?parent=118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/categories?post=118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isatis.asso.fr\/les-maisons-de-la-touche\/wp-json\/wp\/v2\/tags?post=118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}